{"id":4490,"date":"2019-11-27T09:45:58","date_gmt":"2019-11-27T07:45:58","guid":{"rendered":"https:\/\/www.algotronics.fi\/kotisivu\/"},"modified":"2024-01-06T12:41:41","modified_gmt":"2024-01-06T10:41:41","slug":"kotisivu","status":"publish","type":"page","link":"https:\/\/www.algotronics.fi\/fi\/","title":{"rendered":"Etusivu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4490\" class=\"elementor elementor-4490 elementor-3104\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06d949e elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"06d949e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c99b686\" data-id=\"c99b686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6ee70d elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"b6ee70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;autoplay_speed&quot;:2500,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:2000,&quot;centered_slides&quot;:&quot;yes&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/vr-virtuaalitodellisuus\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Seniori VR maailmassa\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/12\/Canva-Senior-Woman-Wearing-Virtual-Reality-Goggles-at-Home-768x511.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/fibernat-2\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"L\u00e4hde: Stefan Elf\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Bild-224-768x1024.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/fibernat-2\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"OptowestNetDesign_Sketch__ver_Algotronics\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/OptowestNetDesign_Sketch__ver_Algotronics-768x540.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/fibernat-2\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"GujeTestbild2 -katu\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/GujeTestbild2-768x658.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Laadukkaiden tuotteiden valmistus\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/IMG_3005-768x576.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/IoT-esineiden%20internet\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Kuva Credit Guje\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/NetProfiler_Proto.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/vr-virtuaalitodellisuus\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Tivoli\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/FunhouseVR-768x432.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Guje_19\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/Guje_19.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/IoT-esineiden%20internet\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Iot\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/11\/iot-768x434.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"\/IoT-esineiden%20internet\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Codeing\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/11\/Codeing-768x512.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Slides Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Seniori VR maailmassa\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/12\/Canva-Senior-Woman-Wearing-Virtual-Reality-Goggles-at-Home-768x511.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"L\u00e4hde: Stefan Elf\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Bild-224-768x1024.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"OptowestNetDesign_Sketch__ver_Algotronics\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/OptowestNetDesign_Sketch__ver_Algotronics-768x540.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"GujeTestbild2 -katu\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/GujeTestbild2-768x658.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Laadukkaiden tuotteiden valmistus\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/IMG_3005-768x576.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Kuva Credit Guje\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/NetProfiler_Proto.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Tivoli\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/FunhouseVR-768x432.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Guje_19\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/Guje_19.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Iot\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/11\/iot-768x434.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Codeing\" style=\"background-image: url(&#039;https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/11\/Codeing-768x512.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c526758 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c526758\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2aecda3\" data-id=\"2aecda3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ace1916 elementor-widget elementor-widget-heading\" data-id=\"ace1916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Tekniikka, joka luo hyvinvointia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a657f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a657f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7ff14c\" data-id=\"e7ff14c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9adb30a elementor-widget elementor-widget-spacer\" data-id=\"9adb30a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6d4135 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a6d4135\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d6d99e\" data-id=\"2d6d99e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-899885c elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"899885c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;Kysy&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDI3NCwidG9nZ2xlIjpmYWxzZX0%3D\">\n\n\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Kysy<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">miten! Minulla on yli 40 vuoden kokemus.<\/span>\n\t\t\t\t\t<\/h3>\n\t\t<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8963086 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8963086\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7c74e4\" data-id=\"c7c74e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40ef91d animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"40ef91d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1638\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-2048x1638.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-8996\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-2048x1638.png 2048w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-300x240.png 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-1024x819.png 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-768x614.png 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/04\/Guje_23_tb_1-1536x1229.png 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Yritt\u00e4j\u00e4 Guje K\u00e4llberg<br>R\u00e4\u00e4t\u00e4l\u00f6idyt tietoj\u00e4rjestelm\u00e4t, ohjelmointi ja haluttaessa elektroniikka ja mentorointi<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c15cf elementor-widget elementor-widget-spacer\" data-id=\"35c15cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1360c5 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a1360c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\">Kolme p\u00e4\u00e4tuotetta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f78b62 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"8f78b62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa77aa1\" data-id=\"aa77aa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eabebe6 elementor-widget elementor-widget-heading\" data-id=\"eabebe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\"><a href=\"https:\/\/www.algotronics.fi\/fibernat-2\/\">Kuitua<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb51d8 elementor-widget elementor-widget-image\" data-id=\"0bb51d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.algotronics.fi\/fibernat-2\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Bild-224-768x1024.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4812\" alt=\"L\u00e4hde: Stefan Elf\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Bild-224-768x1024.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Bild-224-225x300.jpg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">L\u00e4hde: Stefan Elf<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57dbae2 elementor-widget elementor-widget-heading\" data-id=\"57dbae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.algotronics.fi\/fibernat-2\/\">Kuituverkko kyl\u00e4\u00e4n<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dec9ed elementor-align-center elementor-button-success elementor-widget elementor-widget-button\" data-id=\"3dec9ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.algotronics.fi\/fi\/kuitu-verkot\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lue lis\u00e4\u00e4...<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89ceeab elementor-widget elementor-widget-text-editor\" data-id=\"89ceeab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Haluatko kuitua kyl\u00e4\u00e4si tai vaikka<\/strong><strong style=\"color: var( --e-global-color-text ); -webkit-text-size-adjust: 100%;\"> koko kuntaan?<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Ota yhteytt\u00e4! Voin kertoa teille, miten se toimii.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-055973c\" data-id=\"055973c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56304bb elementor-widget elementor-widget-heading\" data-id=\"56304bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\"><a href=\"https:\/\/www.algotronics.fi\/iot-internet-of-things\/\">Iot<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a231cb elementor-widget elementor-widget-spacer\" data-id=\"4a231cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1419997 elementor-widget elementor-widget-video\" data-id=\"1419997\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/IotOnOff.mp4\" autoplay=\"\" loop=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daac725 elementor-widget elementor-widget-spacer\" data-id=\"daac725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d3a4a elementor-widget elementor-widget-heading\" data-id=\"15d3a4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.algotronics.fi\/iot-internet-of-things\/\">Asioiden<br>Internet<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfa331f elementor-align-center elementor-button-success elementor-widget elementor-widget-button\" data-id=\"cfa331f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.algotronics.fi\/fi\/iot-esineiden-internet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lue lis\u00e4\u00e4...<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5779ac8 elementor-widget elementor-widget-text-editor\" data-id=\"5779ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"text-align: center;\"><strong>Nyky\u00e4\u00e4n on sek\u00e4 helppoa ett\u00e4 halpaa yhdist\u00e4\u00e4 asioita Internetiin.<\/strong><\/div>\n<div style=\"text-align: center;\"><strong> <\/strong><\/div>\n<div style=\"text-align: center;\"><b>Ota yhteytt\u00e4, jos sinulla on t\u00e4llaisia tarpeita!<\/b><\/div><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d1ffc47\" data-id=\"d1ffc47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7cf60 elementor-widget elementor-widget-heading\" data-id=\"bc7cf60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\"><a href=\"https:\/\/www.algotronics.fi\/it-support\/\">Mentori<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc8adc elementor-widget elementor-widget-image\" data-id=\"2fc8adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.algotronics.fi\/it-support\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1918\" height=\"1279\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv.jpg\" class=\"attachment-full size-full wp-image-7659\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv.jpg 1918w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv-300x200.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv-1024x683.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv-768x512.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2020\/10\/Support_Help_sv-1536x1024.jpg 1536w\" sizes=\"(max-width: 1918px) 100vw, 1918px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><a href=\"https:\/\/pixabay.com\/users\/anncapictures-1564471\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=1385700\">Valokuva-anncapictures<\/a><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08ff018 elementor-widget elementor-widget-heading\" data-id=\"08ff018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.algotronics.fi\/it-support\/\">Apua IT-asioissa<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-070e1cc elementor-align-center elementor-button-success elementor-widget elementor-widget-button\" data-id=\"070e1cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.algotronics.fi\/fi\/it-tuki\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lue lis\u00e4\u00e4...<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e10fba2 elementor-widget elementor-widget-text-editor\" data-id=\"e10fba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Kukaan ei tied\u00e4 kaikkea. En edes min\u00e4. Mutta tied\u00e4n paljon IT: st\u00e4 ja tietokoneista. Jotain, mit\u00e4 muutkin ovat huomanneet.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Ota yhteytt\u00e4, jos tarvitset apua!<\/strong><strong style=\"color: var( --e-global-color-text );\"> <\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5783df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5783df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c38d1ab\" data-id=\"c38d1ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0064fa elementor-widget elementor-widget-spacer\" data-id=\"b0064fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd1b304 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fd1b304\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\">Mit\u00e4 teen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2323f7b elementor-widget elementor-widget-spacer\" data-id=\"2323f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1ef177 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a1ef177\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-8baf03e\" data-id=\"8baf03e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f76a9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"95f76a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Valokuitua maaseudulle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2588ed elementor-widget elementor-widget-image\" data-id=\"b2588ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem-1024x819.jpg\" class=\"attachment-large size-large wp-image-9282\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem-1024x819.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem-300x240.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem-768x614.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem-1536x1229.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/DraFiberHem.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20fbad elementor-widget elementor-widget-text-editor\" data-id=\"f20fbad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong style=\"color: var( --e-global-color-text ); -webkit-text-size-adjust: 100%;\">Harvaan asutuilla alueilla et\u00e4isyyksill\u00e4 on merkityst\u00e4. Erityisesti langattomissa 4G\/5G verkoissa. L\u00e4hetysnopeutta ei voida parantaa, ellei et\u00e4isyyksi\u00e4 mastoon lyhennet\u00e4. Mutta miten, kun mastoja ei lis\u00e4t\u00e4?<\/strong><\/p>\n<p>Joten jos et saa tarpeeksi nopeutta j\u00e4rjestelm\u00e4\u00e4si, sinun on poistettava ominaisuuksia k\u00e4yt\u00f6st\u00e4. Ja lohduttaa itse\u00e4\u00e4n sill\u00e4, ett\u00e4 &#8221;v\u00e4h\u00e4n on tarpeeksi hyv\u00e4\u00e4, se riitt\u00e4\u00e4 minulle&#8221;.<\/p>\n<p style=\"text-align: center;\"><strong style=\"color: var( --e-global-color-text ); -webkit-text-size-adjust: 100%;\">Ainoa k\u00e4ytett\u00e4viss\u00e4 oleva ratkaisu on optiset kuitukaapelit. Sitten koko perhe voi k\u00e4ytt\u00e4\u00e4 kaikkea Internetiss\u00e4 tas, samaan aikaan ja t\u00e4ydell\u00e4 nopeudella. <\/strong><\/p>\n<p style=\"text-align: center;\"><strong style=\"color: var( --e-global-color-text ); -webkit-text-size-adjust: 100%;\">Sit\u00e4 varten ty\u00f6skentelen maaseudulla.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7642bc9\" data-id=\"7642bc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7f0adc elementor-widget elementor-widget-image\" data-id=\"f7f0adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014-1024x582.jpg\" class=\"attachment-large size-large wp-image-9328\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014-1024x582.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014-300x171.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014-768x437.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014-1536x874.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GodJul2014.jpg 1579w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Luvattu v\u00e4hint\u00e4\u00e4n 200 Mbps<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253b1ca elementor-widget elementor-widget-image\" data-id=\"253b1ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/OptowestPlaner2020-1024x685.png\" class=\"attachment-large size-large wp-image-8664\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/OptowestPlaner2020-1024x685.png 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/OptowestPlaner2020-300x201.png 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/OptowestPlaner2020-768x514.png 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/OptowestPlaner2020.png 1429w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kuituverkko Bromarvissa<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7d5454 elementor-widget elementor-widget-image\" data-id=\"a7d5454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"554\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/FiberSwitch.png\" class=\"attachment-large size-large wp-image-9133\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/FiberSwitch.png 569w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/FiberSwitch-300x292.png 300w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Jokainen kuitukaapeli menee taloon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b872bdb elementor-widget elementor-widget-image\" data-id=\"b872bdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/05\/NordicMobileDataTrans2016-1024x678.jpg\" class=\"attachment-large size-large wp-image-9354\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/05\/NordicMobileDataTrans2016-1024x678.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/05\/NordicMobileDataTrans2016-300x199.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/05\/NordicMobileDataTrans2016-768x508.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/05\/NordicMobileDataTrans2016.jpg 1209w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Mobiilidata lis\u00e4\u00e4ntyy Suomessa eniten<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-91f16e5 elementor-widget elementor-widget-spacer\" data-id=\"91f16e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd495ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd495ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-740dd2f\" data-id=\"740dd2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-361c8f7 elementor-widget elementor-widget-image\" data-id=\"361c8f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/Iot-1-1024x493.jpg\" class=\"attachment-large size-large wp-image-8252\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/Iot-1-1024x493.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/Iot-1-300x144.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/Iot-1-768x370.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/Iot-1.jpg 1350w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9da61f7 elementor-widget elementor-widget-image\" data-id=\"9da61f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"674\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Raspberry-1024x674.jpg\" class=\"attachment-large size-large wp-image-4828\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Raspberry-1024x674.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Raspberry-300x197.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Raspberry-768x505.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/04\/Raspberry.jpg 1304w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-19aaf81\" data-id=\"19aaf81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da44b6c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"da44b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Esineiden internet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a07b40e elementor-widget elementor-widget-video\" data-id=\"a07b40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/IoTfridge1-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\" poster=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/FrysenOk2.jpg\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8893ef elementor-widget elementor-widget-spacer\" data-id=\"a8893ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e35d71a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e35d71a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-22b22ec\" data-id=\"22b22ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3565b83 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3565b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Saa ty\u00f6t tehty\u00e4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cb1c14 elementor-widget elementor-widget-video\" data-id=\"3cb1c14\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/11\/Getting-the-job-done-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5f7db7d\" data-id=\"5f7db7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0e534b elementor-widget elementor-widget-image\" data-id=\"c0e534b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"397\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/Guje_19.png\" class=\"attachment-large size-large wp-image-9146\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/Guje_19.png 513w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2022\/10\/Guje_19-300x232.png 300w\" sizes=\"(max-width: 513px) 100vw, 513px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a817bc8 elementor-widget elementor-widget-image\" data-id=\"a817bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"70\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/12\/cropped-ALGOTRONICS-logo.png\" class=\"attachment-large size-large wp-image-6723\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-95a28b2 elementor-widget elementor-widget-spacer\" data-id=\"95a28b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d22a505 elementor-widget elementor-widget-spacer\" data-id=\"d22a505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-192385c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"192385c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-23f3eb3\" data-id=\"23f3eb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-800f057 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"800f057\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Vapaa-ajan ty\u00f6t<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e6f658 elementor-widget elementor-widget-image\" data-id=\"6e6f658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-1024x768.jpg\" class=\"attachment-large size-large wp-image-9294\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-1024x768.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-300x225.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-768x576.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-1536x1152.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/IMG_0132-e1547913098728-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bf5460 elementor-widget elementor-widget-image\" data-id=\"8bf5460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-768x1024.jpg\" class=\"attachment-large size-large wp-image-9530\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-768x1024.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-225x300.jpg 225w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-1152x1536.jpg 1152w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-1536x2048.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3162-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dea472a elementor-widget elementor-widget-image\" data-id=\"dea472a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-1024x768.jpg\" class=\"attachment-large size-large wp-image-9540\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-1024x768.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-300x225.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-768x576.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-1536x1152.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3018-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7334b25\" data-id=\"7334b25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de9d6af elementor-widget elementor-widget-image\" data-id=\"de9d6af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1024\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-1020x1024.jpg\" class=\"attachment-large size-large wp-image-9288\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-1020x1024.jpg 1020w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-300x300.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-150x150.jpg 150w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-768x771.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-1530x1536.jpg 1530w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2023\/04\/GujeJobb-2040x2048.jpg 2040w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb9d10b elementor-widget elementor-widget-image\" data-id=\"eb9d10b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-768x1024.jpg\" class=\"attachment-large size-large wp-image-9527\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-768x1024.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-225x300.jpg 225w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-1152x1536.jpg 1152w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-1536x2048.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3160-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-329ddc0 elementor-widget elementor-widget-image\" data-id=\"329ddc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"467\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/06\/Guje_VR.jpg\" class=\"attachment-large size-large wp-image-4976\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/06\/Guje_VR.jpg 675w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2019\/06\/Guje_VR-300x208.jpg 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f664e45 elementor-widget elementor-widget-image\" data-id=\"f664e45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-1024x768.jpg\" class=\"attachment-large size-large wp-image-9537\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-1024x768.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-300x225.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-768x576.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-1536x1152.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_3041-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7301d3 elementor-widget elementor-widget-image\" data-id=\"a7301d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"1024\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_0013-920x1024.png\" class=\"attachment-large size-large wp-image-9534\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_0013-920x1024.png 920w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_0013-270x300.png 270w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_0013-768x855.png 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/IMG_0013.png 1295w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c10ab9 elementor-widget elementor-widget-image\" data-id=\"9c10ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3-1024x768.jpg\" class=\"attachment-large size-large wp-image-9519\" alt=\"\" srcset=\"https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3-1024x768.jpg 1024w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3-300x225.jpg 300w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3-768x576.jpg 768w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3-1536x1152.jpg 1536w, https:\/\/www.algotronics.fi\/wp-content\/uploads\/2024\/01\/PA130105-3.jpg 1910w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c66a944 elementor-widget elementor-widget-spacer\" data-id=\"c66a944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Previous Next Tekniikka, joka luo hyvinvointia Kysy miten! Minulla on yli 40 vuoden kokemus. Yritt\u00e4j\u00e4 Guje K\u00e4llbergR\u00e4\u00e4t\u00e4l\u00f6idyt tietoj\u00e4rjestelm\u00e4t, ohjelmointi ja haluttaessa elektroniikka ja mentorointi Kolme p\u00e4\u00e4tuotetta Kuitua Foto: Stefan Elf Kuituverkko kyl\u00e4\u00e4n Lue lis\u00e4\u00e4&#8230; Haluatko kuitua kyl\u00e4\u00e4si tai vaikka koko kuntaan? Ota yhteytt\u00e4! Voin kertoa teille, miten se toimii. Iot https:\/\/www.algotronics.fi\/wp-content\/uploads\/2021\/03\/IotOnOff.mp4 AsioidenInternet Lue lis\u00e4\u00e4&#8230; Nyky\u00e4\u00e4n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-4490","page","type-page","status-publish","hentry","wpbf-post"],"_links":{"self":[{"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/pages\/4490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/comments?post=4490"}],"version-history":[{"count":0,"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/pages\/4490\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.algotronics.fi\/fi\/wp-json\/wp\/v2\/media?parent=4490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}